{"id":357,"date":"2020-09-08T17:34:33","date_gmt":"2020-09-08T15:34:33","guid":{"rendered":"https:\/\/www.testsailhan.fr\/?page_id=357"},"modified":"2026-03-17T18:14:29","modified_gmt":"2026-03-17T17:14:29","slug":"deliberations-et-arretes-municipaux","status":"publish","type":"page","link":"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/","title":{"rendered":"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"357\" class=\"elementor elementor-357\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b127a2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b127a2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c14c1bf\" data-id=\"c14c1bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78d96d8 elementor-widget elementor-widget-spacer\" data-id=\"78d96d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf2059f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf2059f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f1c693\" data-id=\"0f1c693\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ab3c9 elementor-widget elementor-widget-heading\" data-id=\"a5ab3c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b121bcd\" data-id=\"b121bcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67fe345 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"67fe345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mairie-sailhan.fr\/\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACCUEIL<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0904f4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0904f4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e05984c\" data-id=\"e05984c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82cf099 elementor-widget elementor-widget-spacer\" data-id=\"82cf099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8902289 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8902289\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61b1a51\" data-id=\"61b1a51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-45cf0f6\" data-id=\"45cf0f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d91e5d7 elementor-widget elementor-widget-heading\" data-id=\"d91e5d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9lib\u00e9rations<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4b3d26 elementor-widget elementor-widget-heading\" data-id=\"b4b3d26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ann\u00e9e 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b6f2276\" data-id=\"b6f2276\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb9ef12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb9ef12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a2271c\" data-id=\"2a2271c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9d56095\" data-id=\"9d56095\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf0bd91 elementor-widget elementor-widget-toggle\" data-id=\"cf0bd91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2171\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2171\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 5 f\u00e9vrier 2025<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2171\"><p style=\"caret-color: #000000; color: #000000;\"><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/02\/Deliberation-Convention-serviture-RTE-sailhan-saint-lary.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Saint-Lary Soulan et Sailhan.<\/a><\/p><p style=\"caret-color: #000000; color: #000000;\"><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/02\/Deliberation-Convention-serviture-RTE-sailhan-saint-lary-et-tramezaygues.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Trameza\u00efgues, Saint-Lary Soulan et Sailhan.<\/a><\/p><p style=\"caret-color: #000000; color: #000000;\"><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/02\/Deliberation-relative-a-la-redevance-eau-potable-et-a-la-redevance-pour-performance-des-reseaux-deau-potable-pour-2025.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la redevance \u00ab\u00a0Consommation d&rsquo;eau potable\u00a0\u00bb et \u00e0 la redevance pour performance des r\u00e9seaux d&rsquo;eau potable pour l&rsquo;ann\u00e9e 2025.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2172\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2172\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 10 avril 2025<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2172\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2172\"><p>D\u00e9lib\u00e9rations relatives :\u00a0<\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-motion-de-soutien-a-lelectrification-rurale.pdf\" target=\"_blank\" rel=\"noopener\">A l&rsquo;adoption d&rsquo;une motion de soutien \u00e0 l&rsquo;\u00e9lectrification rurale<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-du-compte-administratif-2024.pdf.pdf\" target=\"_blank\" rel=\"noopener\">Au vote du compte administratif 2024 du budget principal<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-compte-de-gestion-2024-BP.pdf\" target=\"_blank\" rel=\"noopener\">Au vote du compte de gestion 2024<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-affection-de-resultats-2024.pdf\" target=\"_blank\" rel=\"noopener\">Au vote d&rsquo;affection des r\u00e9sultats 2024<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-Budget-principal-2025.pdf\" target=\"_blank\" rel=\"noopener\">Au vote du budget principal 2025<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-des-subventions-2025.pdf\" target=\"_blank\" rel=\"noopener\">Au vote des subventions 2025<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-vote-du-taux-dimposition-des-taxes-locales-2025.pdf\" target=\"_blank\" rel=\"noopener\">Au vote des taux d&rsquo;imposition des taxes directes locales 2025<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/04\/Delib-approbation-statuts-SDE.pdf\" target=\"_blank\" rel=\"noopener\">Au vote d&rsquo;approbation des statuts du syndicat d\u00e9partemental d&rsquo;\u00e9lectricit\u00e9 des Hautes-Pyr\u00e9n\u00e9es (SDE65)<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2173\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2173\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 25 juin 2025<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2173\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2173\"><p>D\u00e9lib\u00e9rations relatives :<\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/07\/Deliberation-relative-a-une-demande-de-concession-au-cometieer-communal.pdf\" target=\"_blank\" rel=\"noopener\">A la demande de concession au cimeti\u00e8re communal<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/07\/Deliberation-Deliberation-mise-en-place-dun-pret-bancaire-aupres-du-credit-agricole.pdf\" target=\"_blank\" rel=\"noopener\">A la mise en place d&rsquo;un pr\u00eat bancaire aupr\u00e8s du Cr\u00e9dit Agricole<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/07\/Deliberation-relative-a-lautouatisation-de-la-porte-de-leglise-communale.pdf\" target=\"_blank\" rel=\"noopener\">A l&rsquo;automatisation de la porte de l&rsquo;\u00e9glise communale<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfcd987 elementor-widget elementor-widget-spacer\" data-id=\"dfcd987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-84ba3fe\" data-id=\"84ba3fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d6e1e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d6e1e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-69a578e\" data-id=\"69a578e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-064c066\" data-id=\"064c066\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9592e16 elementor-widget elementor-widget-heading\" data-id=\"9592e16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ann\u00e9e 2024<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cb521bd\" data-id=\"cb521bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d14418e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d14418e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66ffca5\" data-id=\"66ffca5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-107667a\" data-id=\"107667a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56dbcf8 elementor-widget elementor-widget-toggle\" data-id=\"56dbcf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 25 septembre 2024<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9101\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/10\/Deliberations-du-CM-du-25-septembre-2024.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives : au transfert de la comp\u00e9tence \u00ab\u00a0assainissement collectif \u00a0\u00bb du SIAHVA \u00e0 la CCAL et d\u00e9l\u00e9gation de cette comp\u00e9tence de la CCAL au SIAHVA, au reversement de l&rsquo;exc\u00e9dent de fonctionnement du SIAHVA aux communes membres, <\/a><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/10\/Deliberations-du-CM-du-25-septembre-2024.pdf\" target=\"_blank\" rel=\"noopener\">\u00e0 la mise en place de la redevance sp\u00e9ciale forfaitaire pour les collectivit\u00e9s et leurs \u00e9tablissements publics, \u00e0 la fermeture d\u00e9finitive du pr\u00e9au et de la cour de l&rsquo;ancienne \u00e9cole, \u00e0 la d\u00e9cision modificative budg\u00e9taire, \u00e0 la proposition d&rsquo;achat de la Commune d&rsquo;une bande de la parcelle A1050 quartier le Garet, aux travaux sur le r\u00e9seau pluvial bien de Cachou, \u00e0 l&rsquo;interdiction de stationnement des v\u00e9hicules route de Saint-Lary, \u00e0 l&rsquo;isolation de la cage d&rsquo;escalier de la Mairie.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9102\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-9102\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 30 mai 2024<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9102\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-9102\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/06\/Deliberations-du-CM-30-mai-24.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 la demande de subvention du club VTT aurois, \u00e0 la fermeture d\u00e9finitive du pr\u00e9au de l&rsquo;ancienne \u00e9cole, .<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9103\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-9103\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 3 avril 2024<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9103\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-9103\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/07\/Deliberations-du-3-avril-2024-.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives au vote du compte de gestion 2023 (Budget Principal), vote du compte de gestion 2023 (Budget Principal), vote de l&rsquo;affectation des r\u00e9sultats 2023, vote du Budget principal 2024, vote des subventions 2024, vote des indemnit\u00e9s du maire et des adjoints, vote d&rsquo;adh\u00e9sion \u00e0 l&rsquo;association \u00ab\u00a0Itin\u00e9raires Libert\u00e9 Pyr\u00e9n\u00e9es\u00a0\u00bb, vote de la vente intervenue entre \u00ab\u00a0Ladrix-Garcia\u00a0\u00bb et la commune de Sailhan, vote de la demande d&rsquo;exon\u00e9ration de loyer demand\u00e9e par monsieur Coustalat Alain.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87d4188 elementor-widget elementor-widget-spacer\" data-id=\"87d4188\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-edb95c9\" data-id=\"edb95c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86f9938 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86f9938\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b2bb540\" data-id=\"b2bb540\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea234e6\" data-id=\"ea234e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-361c3f5 elementor-widget elementor-widget-heading\" data-id=\"361c3f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ann\u00e9e 2023<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f3a851\" data-id=\"2f3a851\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b0bec3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b0bec3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-594fd90\" data-id=\"594fd90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ab1b86c\" data-id=\"ab1b86c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc9462d elementor-widget elementor-widget-toggle\" data-id=\"fc9462d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2641\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2641\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 19 d\u00e9cembre 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2641\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/01\/Adhesion-SIVOM.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 l&rsquo;adh\u00e9sion des communes de Bazus-Aure, Trameza\u00efgues et Guchen au SIVOM de la vall\u00e9e d&rsquo;Aure.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/01\/Demande-de-subvention-DETR.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la demande de subvention DETR 2024 et \u00e0 la signal\u00e9tique intracommunale.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/01\/Versement-subvention-exceptionnelle-a-lasso-les-pitchouins.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative au versement d&rsquo;une subvention exceptionnelle \u00e0 l&rsquo;association \u00ab\u00a0Les Pitchouns de Sailhan\u00a0\u00bb pour la participation au forfait ski.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/01\/Deliberation-subvention-FAR-goudronnage-bies-du-village-.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la demande de subvention FAR 2024 pour le goudronnage des bi\u00e9s du village.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/02\/Delib-mandat-depenses-dinvestissement-du-19-decembre-2023.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration autorisant le Maire \u00e0 engager, liquider et mandater les d\u00e9penses d&rsquo;investissement (dans la limite du quart des cr\u00e9dits ouverts au budget de l&rsquo;exercice pr\u00e9c\u00e9dent).<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2642\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2642\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 28 septembre 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2642\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2642\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/10\/Deliberations-du-28-septembre-2023.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 l&rsquo;acquisition d&rsquo;une case au columbarium, \u00e0 la r\u00e9ouverture de la m\u00e9diath\u00e8que communale, au versement d&rsquo;une subvention exceptionnelle \u00e0 l&rsquo;association \u00ab\u00a0Les amis du moulin de la Mousqu\u00e8re\u00a0\u00bb et \u00e0 l&rsquo;ONF &#8211; Vente de bois en ligne &#8211; Fixation du prix plancher.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2643\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2643\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 1er juin 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2643\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2643\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/06\/Deliberations-seance-du-01-06.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives au Syndicat D\u00e9partemental d&rsquo;Energie concernant l&rsquo;\u00e9clairage public, \u00e0 la Tr\u00e9sorerie Aure-Louron, \u00e0 la contribution au SDIS (restitution de la comp\u00e9tence aux communes) et au vote du huit clos pour la s\u00e9ance du conseil municipal.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2644\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2644\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 11 avril 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2644\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2644\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/04\/Deliberations-du-11-avril-2023.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives aux votes du Compte de Gestion 2022 (budget principal), du Compte Administratif 2022 (budget principal), de l&rsquo;affection des r\u00e9sultats 2022, des taux d&rsquo;imposition des taxes directes locales 2023, du Budget Principal 2023 et des subventions 2023.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2645\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2645\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 22 f\u00e9vrier 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2645\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2645\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/03\/Deliberations-du-22-fevrier-2023.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 l&rsquo;autorisation pour le maire \u00e0 engager, liquider et mandater les d\u00e9penses d&rsquo;investissement (dans la limite du quart des cr\u00e9dits ouverts au budget de l&rsquo;exercice pr\u00e9c\u00e9dent), \u00e0 la demande de subvention FAR 2023 et DETR 2023, au groupement de commande pour le sch\u00e9ma directeur d&rsquo;eau potable, \u00e0 l&rsquo;acquisition des parcelles A233 et A234 rue d&rsquo;Ens et au droit de pr\u00e9emption sur le foncier b\u00e2ti et non b\u00e2ti.\u00a0<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4ee31d elementor-widget elementor-widget-spacer\" data-id=\"b4ee31d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcfef90 elementor-widget elementor-widget-heading\" data-id=\"fcfef90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ann\u00e9e 2022<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f2d282\" data-id=\"2f2d282\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-862d084 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"862d084\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-beb8644\" data-id=\"beb8644\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-97191db\" data-id=\"97191db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b805e85 elementor-widget elementor-widget-toggle\" data-id=\"b805e85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1921\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1921\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 7 d\u00e9cembre 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1921\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1921\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/12\/Deliberations-economie-denergie-sur-leclairage-public-et-les-batiments-c.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie sur l&rsquo;\u00e9clairage public et les b\u00e2timents communaux, \u00e0 l&rsquo;approbation de la modification des statuts du SIAHVA, \u00e0 l&rsquo;approbation des statuts du Syndicat D\u00e9partemental d&rsquo;Energie, \u00e0 \u00a0la subvention vers\u00e9e aux Pitchouns de Sailhan pour la participation de la commune aux forfaits de ski des enfants.\u00a0<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/12\/Deliberation-caution-appartement-communal-n\u00b02-du-Presbytere-et-decision-modificative-budgetaire-n\u00b02.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 la caution de l&rsquo;appartement communal n\u00b02 r\u00e9sidence du Presbyt\u00e8re, de la d\u00e9cision modificative budg\u00e9taire n\u00b02.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/01\/Deliberation-Decision-modificative-budgetaire-n\u00b03.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la d\u00e9cision de modification budg\u00e9taire n\u00b03.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/01\/Delib-7-decembre-2022.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la d\u00e9cision de modification budg\u00e9taire n\u00b05.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1922\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1922\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 9 novembre 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1922\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1922\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/12\/Deliberation-modif-budgetaire-N\u00b01.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 une d\u00e9cision modificative budg\u00e9taire n\u00b01.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1923\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1923\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 12 octobre 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1923\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1923\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/11\/Delib-nomenclature-M57-12-oct-22-N\u00b0-2022-31.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 l&rsquo;adoption de la nomenclature budg\u00e9taire et comptable M57 au 1er janvier 2023.\u00a0<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/11\/DelibTravauxcommunaux-N\u00b02022-32.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la priorisation des travaux 2023-2026.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/11\/Delib-aire-loisirs-PI-N\u00b02022-33.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la r\u00e9alisation d&rsquo;une aire de loisirs chemin au du Pi.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/11\/Delib-versement-Es-de-Sailho-N\u00b0-2022-34.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative au versement exceptionnel au comit\u00e9 des F\u00eates \u00ab\u00a0Es de Sailho\u00a0\u00bb.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1924\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1924\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 7 juillet 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1924\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1924\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/08\/Deliberations-seance-7-juillet.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations sur le site de Caneilles (convention de mandat pour la passation d&rsquo;appel \u00e0 projets entre les communes de Saint-Lary Soulan et de Sailhan), SDE-EP rural 2022 (pose de deux radars p\u00e9dagogiques sur la route de Saint-Lary et la route d&rsquo;Azet), Documents d&rsquo;Information sur les Risques Majeurs (convention entre le PETR du Pays des Restes et la commune de Sailhan) et sur l&rsquo;\u00e9tat d&rsquo;assiette 2022 (additifs Saint-Lary Soulan et Sailhan).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/08\/Deliberation-du-7-juillet-2022-Loyer.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 l&rsquo;indemnisation d&rsquo;un mois de loyer \u00e0 Monsieur ALEGRE LOPEZ Patrice.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1925\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1925\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 16 mai 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1925\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1925\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/07\/Deliberations-16-mai-2022.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 la publication des actes municipaux pris par la commune de Sailhan et \u00e0 la d\u00e9nomination d&rsquo;une voie communale.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1926\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1926\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 14 avril 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1926\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1926\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/04\/Deliberations-sailhan.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives aux votes du compte de gestion et du compte administratif 2021 (budget principal), vote de l&rsquo;affectation des r\u00e9sultats 2021, vote du budget principal 2022, vote des subventions 2022, indemnit\u00e9s du Maire et de ses adjoints, dur\u00e9e des amortissements, collecte des ordures m\u00e9nag\u00e8res sur la commune de Sailhan.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/07\/Deliberation-du-14-avril-2022.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative au vote des taux d&rsquo;imposition des taxes locales 2022.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1927\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1927\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 23 f\u00e9vrier 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1927\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1927\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/03\/Deliberations-du-23-fevrier-2022.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 la r\u00e9habilitation de la mairie et de la m\u00e9diath\u00e8que, prestation de la maintenance du site internet communal-paiement mensuel, convention entre la Commune et la m\u00e9diath\u00e8que \u00ab\u00a0Au fournil de Sailhan\u00a0\u00bb.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/03\/Deliberation-du-23-fevrier-2022-2.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 la r\u00e9alisation d&rsquo;audits \u00e9nerg\u00e9tiques par le Syndicat D\u00e9partemental d&rsquo;Energie des Hautes-Pyr\u00e9n\u00e9es.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1928\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1928\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 5 janvier 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1928\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1928\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/01\/Deliberations-du-5-janvier-2022.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 la modification des statuts du SIVOM de la vall\u00e9e d&rsquo;Aure, du transfert de la comp\u00e9tence \u00ab\u00a0signalisation lumineuse tricolore \u00a0\u00bb au Syndicat D\u00e9partemental d&rsquo;Energie 65 \u00e0 compter du 5 janvier 2022, de la mise en place de radars p\u00e9dagogiques route de Saint-Lary Soulan et route d&rsquo;Estensan, z\u00e9ro artificialisation des sols : les territoires ruraux et de montagne p\u00e9nalis\u00e9s, \u00e9lection du troisi\u00e8me adjoint au maire, tableau du Conseil Municipal.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1013f elementor-widget elementor-widget-spacer\" data-id=\"6c1013f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8618ec2 elementor-widget elementor-widget-heading\" data-id=\"8618ec2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ann\u00e9e 2021<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-68f846d\" data-id=\"68f846d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbb1d3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbb1d3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d4c3b6d\" data-id=\"d4c3b6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42b19ad\" data-id=\"42b19ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddd0ff1 elementor-widget elementor-widget-toggle\" data-id=\"ddd0ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2321\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2321\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 2 d\u00e9cembre 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2321\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/12\/Deliberations-du-2-dec-2021.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives \u00e0 une d\u00e9cision modificative du budget principal et \u00e0 une requ\u00eate introductive d&rsquo;instance adress\u00e9e au Tribunal Administratif de Pau par Monsieur FERRAS Lucien.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/01\/Deliberation-du-2-decembre-2021.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 une modification du budget principal.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2322\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2322\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 21 octobre 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2322\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/11\/DELIBERATIONS.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations relatives : circulation sur les chemins de Saint-Lary, Bourisp, la Via de Vielle, Estensan et de la travers\u00e9e eu moulin de la Mousqu\u00e8re; du plan de d\u00e9neigement et de l&rsquo;attribution de la subvention \u00e0 l&rsquo;association \u00ab\u00a0Les Pitchouns\u00a0\u00bb de Sailhan<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2323\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2323\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 14 septembre 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2323\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/09\/Deliberations-Seance-du-14-septembre.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations de la s\u00e9ance du conseil municipal du 14 septembre 2021 relatives \u00e0 : la proposition de convention entre les Hauts de Saint-Lary et la commune de Sailhan, la prestation maintenance du site internet communal, l&rsquo;acquisition de la parcelle A 368 situ\u00e9e chemin du Pi, la location de l&rsquo;appartement communal n\u00b01 situ\u00e9 dans la r\u00e9sidence de l&rsquo;\u00e9cole et l&rsquo;implantation de poteaux par l&rsquo;entreprise t\u00e9l\u00e9phonique Free dans l&rsquo;enceinte de la commune.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/10\/Cabane-de-chasse-demande-de-bail-de-Joseph-RIGOLE-.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration relative \u00e0 une demande d&rsquo;attribution d&rsquo;une cabane de chasse \u00e9manant de Monsieur RIGOLE Joseph.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2324\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2324\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 16 juillet 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2324\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2324\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/07\/Deliberations-Sailhan-2.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations de la s\u00e9ance du Conseil Municipal du 16 juillet 2021.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2325\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2325\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 6 mai 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2325\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2325\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/05\/Seance-du-06-mai.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations du Conseil Municipal du 6 mai 2021<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/06\/Don-de-la-Mediatheque-de-Sailhan-au-profit-de-la-commune.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration du Conseil Municipal du 6 mai 2021 relative au don de la M\u00e9diath\u00e8que de Sailhan au profit de la commune<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2326\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2326\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 21 avril 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2326\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2326\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/05\/Deliberations-du-Conseil-Municipal-du-1er-avril-2021-2.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations du Conseil Municipal du 21 avril 2021<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2327\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2327\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 25 f\u00e9vrier 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2327\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2327\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/06\/Delib-du-25-fevrier-2021.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration du Conseil Municipal du 25 f\u00e9vrier 2021<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2328\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2328\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 1er avril 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2328\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2328\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/05\/Deliberations-du-Conseil-Municipal-du-1er-avril-2021-1.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9rations du Conseil Municipal du 1er avril 2021<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2329\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2329\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">S\u00e9ance du 29 janvier 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2329\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2329\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/02\/Deliberations-CM-du-29-janvier.pdf\" target=\"_blank\" rel=\"noopener\">D\u00e9lib\u00e9ration autorisant le Maire \u00e0 engager, liquider et mandater les d\u00e9penses d&rsquo;investissement (dans la limite du quart des cr\u00e9dits ouverts au budget de l&rsquo;exercice pr\u00e9c\u00e9dent).<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f63e289\" data-id=\"f63e289\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f416c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f416c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e866063\" data-id=\"e866063\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95bf452 elementor-widget elementor-widget-spacer\" data-id=\"95bf452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a30843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a30843\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c53f67\" data-id=\"1c53f67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6d6dfed\" data-id=\"6d6dfed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a88aaa7 elementor-widget elementor-widget-heading\" data-id=\"a88aaa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les arr\u00eat\u00e9s municipaux <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ca5ab2f\" data-id=\"ca5ab2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2caccf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2caccf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4804a80\" data-id=\"4804a80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d5b0241\" data-id=\"d5b0241\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-672422d elementor-widget elementor-widget-toggle\" data-id=\"672422d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1081\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1081\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux 2025<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1081\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1081\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/03\/Arrete-de-divagation-des-chiens-et-dejections-canines-du-17-mars-2025.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de divagation des chiens sur le domaine communal et r\u00e8glementation des d\u00e9jections canines (14 mars 2025).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/05\/Arrete-temporaire-stationnement-ecole-Garet.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire de stationnement dans l&rsquo;ancienne cour de l&rsquo;\u00e9cole au parking Garet pour travaux (16 mai 2025).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/06\/arrete-stationnement-ecole-juin-2025.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction de stationnement dans la cour de l&rsquo;ancienne \u00e9cole (transhumance 2025 &#8211; le 3 juin 2025).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/06\/Arrete-de-fermeture-provisoire-dans-lespace-du-Moulin-de-la-Mousquere-.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 provisoire de fermeture de l&rsquo;espace du Moulin de la Mousqu\u00e8re (Feu de la Saint-Jean &#8211; 27 juin 2025)<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/07\/Arrete-dinterdiction-de-stationnement-dans-la-cour-de-lancienne-ecole-juillet-2025.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction de stationnement dans la cour de l&rsquo;ancienne \u00e9cole (soir\u00e9e Moules Frites &#8211; juillet 2025)<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/07\/Arrete-circulation-chemin-du-Pi-juillet-2025.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de voirie r\u00e8glementant \u00a0la circulation chemin du Pi.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/08\/Arrete-temporaire-dinterdiction-de-stationnement-au-Moulin-de-la-Mousquere.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire d&rsquo;interdiction de stationnement au moulin de la Mousqu\u00e8re (feu d&rsquo;artifice et c\u00e9r\u00e9monie au monument aux morts &#8211; ao\u00fbt)<\/a>.<\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/08\/Arrete-temporaire-dinterdiction-de-stationnement-dans-la-cour-de-lancienne-ecole.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire d&rsquo;interdiction de stationnement dans la cour de l&rsquo;ancienne \u00e9cole (f\u00eate locale et vide-grenier &#8211; ao\u00fbt)<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/11\/ARRETE-temporaire-de-circulation-sur-la-rue-principale-.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire de circulation sur la rue principale (r\u00e9fection toiture novembre 2025)<\/a><\/p><p>Arr\u00eat\u00e9 de modification de <a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2025\/11\/Arrete-de-modification-de-la-circulation-de-la-place-de-lecole-a-la-rue-de-Chutole.pdf\" target=\"_blank\" rel=\"noopener\">la circulation de la place de l&rsquo;\u00e9cole \u00e0 la rue de Chulote (novembre 2025).<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1082\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1082\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux 2024<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1082\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1082\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/08\/Arrete-temporaire-eglise-et-moulin.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction temporaire de stationnement sur la place de l&rsquo;\u00e9glise et au moulin de la Mousqu\u00e8re.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/04\/Arrete-stationnement-ancien-preau-ecole-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction de stationnement sous le pr\u00e9au de l&rsquo;ancienne \u00e9cole.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/01\/Arrete-reglementation-circulation-hcemin-du-Pi.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de police portant r\u00e9glementation de la circulation chemin du Pi.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/07\/Arrete-082024.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire d&rsquo;interdiction du stationnement dans la cour de l&rsquo;ancienne \u00e9cole (vide grenier et f\u00eate locale)<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/09\/Arrete-permanent-portant-interdiction-de-stationnement-a-lentree-du-village-route-de-saint-Lary.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal permanent portant interdiction de stationnement \u00e0 l&rsquo;entr\u00e9e du village route de Saint-Lary.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/10\/Stationnement-parking-du-Garet.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal permanent portant r\u00e9glementation du stationnement au parking du Garet.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/10\/Stationnement-dans-la-cour-de-lancienne-ecole-.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal permanent portant r\u00e9glementation du stationnement dans la cour de l&rsquo;ancienne \u00e9cole.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2024\/11\/ARRETE-TEMPORAIRE-DE-CIRUCULATION-SUR-LA-ROUTE-PRINCIPALE-22-nov-24.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire de circulation sur la route principale (du 27 novembre au 11 d\u00e9cembre 2024).<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1083\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1083\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux de 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1083\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1083\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/03\/at11_20230322_rd25_saint-lary-sailhan_-refection-de-tranchee.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire r\u00e9glementant la circulation sur la route d\u00e9partementale n\u00b025 sur les territoires des communes de Sailhan et de Saint-Lary Soulan (tranch\u00e9e).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2023\/03\/Reglementation-de-la-circulation-sur-la-route-principale.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de police portant sur la r\u00e9glementation de la circulation sur la rue principale.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1084\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1084\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1084\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1084\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/01\/Arrete-de-delegation-de-fonction-aux-adjoints.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de d\u00e9l\u00e9gation de fonction aux adjoints &#8211; D\u00e9l\u00e9gation de signatures.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/05\/Arrete-de-police-portant-reglementation-de-la-circulation-sur-la-route-principale.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de police portant r\u00e9glementation de la circulation sur la route principale.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Arrete-stationnement-preau.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction de stationnement sous le pr\u00e9au de l&rsquo;ancienne \u00e9cole (transhumance 2022).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Scan_0015.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 sur la r\u00e9glementation de la circulation et du stationnement en vue du passage du Tour de France le 20 juillet 2022.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Reglementation.-circulation-Patou-Trail-18-et-19-juin.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 temporaire de r\u00e9glementation de la circulation sur les routes d\u00e9partementales et communales ouvertes \u00e0 la circulation publique sur le territoire communal de Sailhan en vue de la manifestation d\u00e9nomm\u00e9e Patou Trail des 18 et 19 juin 2022.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Arrete-portant-modification-de-la-circulation-temporaire-sur-la-commune-de-Sailhan-Travaux-Fibre-optique.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 portant modification temporaire de la circulation sur la commune de Sailhan pour la r\u00e9alisation des travaux d&rsquo;installation de la fibre optique.<\/a><\/p><p>Arr\u00eat\u00e9s temporaires portant r\u00e9glementation de la circulation sur la commune de Sailhan <a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Arrete-relatif-a-la-cirulation-pour-lEnduro-dAure.pdf\" target=\"_blank\" rel=\"noopener\">lors du passage de l&rsquo;Enduro d&rsquo;Aure <\/a>et de la <a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/06\/Arrete-concerna-tla-circulation-pour-le-passage-de-la-Haute-Route-des-Pyrenees-2022.pdf\" target=\"_blank\" rel=\"noopener\">Haute Route des Pyr\u00e9n\u00e9es 2022<\/a><\/p><p>Arr\u00eat\u00e9s municipaux d&rsquo;interdiction temporaire de stationnement sous le pr\u00e9au de l&rsquo;ancienne \u00e9cole : <a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/07\/Arrete-dinterdiction-de-stationnement-sous-le-preau-de-la-cour-de-lancienne-ecole-du-18-au-26-juillet-inclus.pdf\" target=\"_blank\" rel=\"noopener\">Tour de France et D\u00e9baltou<\/a> &#8211; <a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/07\/Arrete-dinterdiction-de-stationnement-sous-le-preau-de-la-cour-de-lancienne-lecole-13-et-14-aout-2022.pdf\" target=\"_blank\" rel=\"noopener\">F\u00eate locale<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/07\/Arrete-reglementation-circulation-sur-la-route-principale.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 de police r\u00e9glementant la circulation sur la route principales entre le 26 juillet et le 29 juillet.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/08\/Arrete-circulation-fete-de-Sailhan.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal r\u00e9glementant le stationnement sour le pr\u00e9au de l&rsquo;ancienne \u00e9cole lors de la f\u00eate de Sailhan.<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/08\/Reglementation-circulation-preau-Aout-2022.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 d&rsquo;interdiction de stationnement sous le pr\u00e9au et dans l&rsquo;ancienne cour de l&rsquo;\u00e9cole (triathlon 2022).<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2022\/08\/Arrete-circulation-Triathlon-2022.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal temporaire r\u00e9glementant la circulation sur les routes d\u00e9partementales et communales de la commune de Sailhan (Triathlon 2022).<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1085\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1085\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1085\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1085\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/11\/Arrete-permanent-reglementant-la-circulation-sur-le-chemin-de-Bourisp.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal permanent r\u00e9glementant la circulation des v\u00e9hicules \u00e0 moteur sur le chemin de Bourisp dans la commune de Sailhan<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/11\/Reglementation-de-la-cirulation-chemin-Via-de-Vielle.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal r\u00e9glementant la circulation des personnes et des v\u00e9hicules sur le chemin de la Via de Vielle sur la commune de Sailhan<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/11\/Arrete-reglementant-la-ciruclation-sur-le-chemin-de-Saint-Lary.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal r\u00e9glementant la circulation des v\u00e9hicules et des promeneurs sur le chemin de Saint-Lary sur la commune de Sailhan<\/a><\/p><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2021\/11\/Circulation-Estensan.pdf\" target=\"_blank\" rel=\"noopener\">Arr\u00eat\u00e9 municipal permanent r\u00e9glementant la circulation des v\u00e9hicules \u00e0 deux roues et moteur et les recommandations pour les promeneurs sur le chemin d&rsquo;Estensan et dans la travers\u00e9e du moulin de la Mousqu\u00e8re<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1086\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1086\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Arr\u00eat\u00e9s municipaux 2020<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1086\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1086\"><p><a href=\"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2020\/12\/Arretes-municipaux.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e8glementation du stationnement : sur la place Bertrand Menvielle, sur la place de l&rsquo;\u00e9cole, sur le site du moulin de la Mousqu\u00e8re;\u00a0R\u00e9ouverture de l&rsquo;\u00e9glise suite au d\u00e9confinement; Circulation des deux roues et des pi\u00e9tons interdite sur le chemin de Caneilles du lundi 14 d\u00e9cembre au mercredi 23 d\u00e9cembre inclus.<\/a><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/12\/Arrete-n\u00b027-2020.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e9ouverture du b\u00e2timent de la mairie et de la m\u00e9diath\u00e8que.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/ARRETE-21-2020-PREAU-MAIRIE-2.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e9glementation du stationnement et de l&rsquo;utilisation du pr\u00e9au de la mairie.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/arrete-22-2020-cour-ecole.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e9glementation du stationnement dans la cour et sous le pr\u00e9au de l&rsquo;ancienne \u00e9cole.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/Arrete-20-2020.pdf\" target=\"_blank\" rel=\"noopener\">Reprise d&rsquo;une concession en \u00e9t\u00e9 d&rsquo;abandon.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/Arrete-stationnement-rue-ENS.pdf\" target=\"_blank\" rel=\"noopener\">Restriction de stationnement en p\u00e9riode hivernale sur la route d&rsquo;Ens.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/Arrete-Fermeture-de-leglise.pdf\" target=\"_blank\" rel=\"noopener\">Fermeture de l&rsquo;\u00e9glise suite \u00e0 la pand\u00e9mie de Covid-19.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/Arrete-mesures-covid.pdf\" target=\"_blank\" rel=\"noopener\">Mesures prises suite \u00e0 l&rsquo;annonce du reconfinement.<\/a><\/span><\/p><p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/10\/Circulation-pietons-et-vetetistes-sur-Caneilles.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e9glementation de la circulation des pi\u00e9tons et v\u00e9t\u00e9tistes sur le chemin de Caneilles.<\/a><\/span><\/p><p><a href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/Arrete-07.20-Bie-Dessus.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">Interdiction de stationnement au Bi\u00e9 de Dessus.<\/span><\/a><\/p><p><a href=\"https:\/\/www.mairie-sailhan.fr\/wp-content\/uploads\/2020\/11\/arrete-14.2020-CHUTOLE.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">Interdiction de stationnement rue de Chutole.<\/span><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41e64ef\" data-id=\"41e64ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc19d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bc19d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32c1a65\" data-id=\"32c1a65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50bdc35 elementor-widget elementor-widget-spacer\" data-id=\"50bdc35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bed2c86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bed2c86\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6360acad\" data-id=\"6360acad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2965bb elementor-widget elementor-widget-heading\" data-id=\"6d2965bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mairie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c4a930 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"44c4a930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Place Bertrand Menvielle<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">65170 Sailhan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">05 62 39 51 13<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">commune-de-sailhan@orange.fr<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4b63124f\" data-id=\"4b63124f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f19d690 elementor-widget elementor-widget-heading\" data-id=\"2f19d690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.mairie-sailhan.fr\/index.php\/mentions-legales\/\">Mentions legales<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-58721407\" data-id=\"58721407\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47f850a3 elementor-widget elementor-widget-heading\" data-id=\"47f850a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Social Media<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-516a14b3 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"516a14b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c1104d1\" href=\"https:\/\/www.facebook.com\/people\/Mairie-de-Sailhan\/100088254394758\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1893ab4\" href=\"http:\/\/instagram.com\/sailhan_officiel\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4c54e670\" data-id=\"4c54e670\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ef8bc24 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2ef8bc24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mairie-sailhan.fr\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACCUEIL<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux ACCUEIL D\u00e9lib\u00e9rations Ann\u00e9e 2025 S\u00e9ance du 5 f\u00e9vrier 2025 D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Trameza\u00efgues, Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"h5ap_radio_sources":[],"footnotes":""},"class_list":["post-357","page","type-page","status-publish","hentry","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr\" \/>\n<meta property=\"og:description\" content=\"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux ACCUEIL D\u00e9lib\u00e9rations Ann\u00e9e 2025 S\u00e9ance du 5 f\u00e9vrier 2025 D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Trameza\u00efgues, Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/\" \/>\n<meta property=\"og:site_name\" content=\"mairie-sailhan.fr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T17:14:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/index.php\\\/deliberations-et-arretes-municipaux\\\/\",\"url\":\"https:\\\/\\\/mairie-sailhan.fr\\\/index.php\\\/deliberations-et-arretes-municipaux\\\/\",\"name\":\"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#website\"},\"datePublished\":\"2020-09-08T15:34:33+00:00\",\"dateModified\":\"2026-03-17T17:14:29+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mairie-sailhan.fr\\\/index.php\\\/deliberations-et-arretes-municipaux\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#website\",\"url\":\"https:\\\/\\\/mairie-sailhan.fr\\\/\",\"name\":\"mairie-sailhan.fr\",\"description\":\"Mairie de Sailhan\",\"publisher\":{\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mairie-sailhan.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#organization\",\"name\":\"mairie-sailhan.fr\",\"url\":\"https:\\\/\\\/mairie-sailhan.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mairie-sailhan.fr\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-800px-Blason_ville_fr_Sailhan_65.svg.png\",\"contentUrl\":\"https:\\\/\\\/mairie-sailhan.fr\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-800px-Blason_ville_fr_Sailhan_65.svg.png\",\"width\":800,\"height\":878,\"caption\":\"mairie-sailhan.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/mairie-sailhan.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr","og_description":"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux ACCUEIL D\u00e9lib\u00e9rations Ann\u00e9e 2025 S\u00e9ance du 5 f\u00e9vrier 2025 D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 la convention de servitudes du r\u00e9seau de transport d&rsquo;\u00e9lectricit\u00e9 (RTE)\/ communes de Trameza\u00efgues, Saint-Lary Soulan et Sailhan. D\u00e9lib\u00e9ration relative \u00e0 [&hellip;]","og_url":"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/","og_site_name":"mairie-sailhan.fr","article_modified_time":"2026-03-17T17:14:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/","url":"https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/","name":"D\u00e9lib\u00e9rations et arr\u00eat\u00e9s municipaux - mairie-sailhan.fr","isPartOf":{"@id":"https:\/\/mairie-sailhan.fr\/#website"},"datePublished":"2020-09-08T15:34:33+00:00","dateModified":"2026-03-17T17:14:29+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mairie-sailhan.fr\/index.php\/deliberations-et-arretes-municipaux\/"]}]},{"@type":"WebSite","@id":"https:\/\/mairie-sailhan.fr\/#website","url":"https:\/\/mairie-sailhan.fr\/","name":"mairie-sailhan.fr","description":"Mairie de Sailhan","publisher":{"@id":"https:\/\/mairie-sailhan.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mairie-sailhan.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mairie-sailhan.fr\/#organization","name":"mairie-sailhan.fr","url":"https:\/\/mairie-sailhan.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mairie-sailhan.fr\/#\/schema\/logo\/image\/","url":"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2020\/09\/cropped-800px-Blason_ville_fr_Sailhan_65.svg.png","contentUrl":"https:\/\/mairie-sailhan.fr\/wp-content\/uploads\/2020\/09\/cropped-800px-Blason_ville_fr_Sailhan_65.svg.png","width":800,"height":878,"caption":"mairie-sailhan.fr"},"image":{"@id":"https:\/\/mairie-sailhan.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/pages\/357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":0,"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/pages\/357\/revisions"}],"wp:attachment":[{"href":"https:\/\/mairie-sailhan.fr\/index.php\/wp-json\/wp\/v2\/media?parent=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}